{"id":4230,"date":"2022-03-30T16:30:45","date_gmt":"2022-03-30T20:30:45","guid":{"rendered":"https:\/\/resources.purolator.com\/?p=4230"},"modified":"2023-10-20T13:53:21","modified_gmt":"2023-10-20T17:53:21","slug":"inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables","status":"publish","type":"post","link":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/","title":{"rendered":"Inspirer le changement et \u00ab Combattre Les Pr\u00e9jug\u00e9s \u00bb avec une entreprise de maillots de bain durables"},"content":{"rendered":"<p>Les maillots de bain de <a href=\"https:\/\/sisterlyswim.com\/\" target=\"_blank\" rel=\"noopener\">Sisterly\u00a0Swimwear<\/a> prennent d\u2019assaut le march\u00e9. Pour c\u00e9l\u00e9brer <a href=\"https:\/\/resources.purolator.com\/fr\/journee-internationale-des-femmes\/\" target=\"_blank\" rel=\"noopener\">la Journ\u00e9e internationale des femmes<\/a>, nous avons donn\u00e9 la parole \u00e0 deux\u00a0s\u0153urs passionn\u00e9es dont les talents d\u2019entrepreneurs ont permis de cr\u00e9er une petite entreprise des plus novatrices, que nous sommes fiers de soutenir.<\/p>\n<p>Isabelle et Olivia sont les cr\u00e9atrices judicieuses et inspirantes derri\u00e8re cette entreprise de maillots de bain durables. Cindy\u00a0Bailey, notre directrice du d\u00e9veloppement durable de l\u2019entreprise, a eu l\u2019occasion de s\u2019entretenir avec ce duo dynamique afin de comprendre leur motivation, la direction de leur entreprise et les choses apprises en cours de route.<\/p>\n<blockquote class=\"altbq\">\u00ab Nous voulons cr\u00e9er des maillots de bain qui \u00e9pousent toutes les silhouettes \u00bb \u2013 Isabelle Leger, cofondatrice de Sisterly Swimwear<\/blockquote>\n<h2>Des femmes inspirantes qui luttent contre les pr\u00e9jug\u00e9s<\/h2>\n<p>Ces deux\u00a0s\u0153urs ont uni leurs forces et leurs int\u00e9r\u00eats pour cr\u00e9er une entreprise dont elles peuvent \u00eatre fi\u00e8res, gr\u00e2ce \u00e0 leur impressionnante gamme de maillots de bain inclusifs qui favorisent la positivit\u00e9 corporelle et inspirent les femmes partout sur la plan\u00e8te.<\/p>\n<p>En plus d\u2019\u00eatre fabriqu\u00e9s selon des pratiques commerciales durables, tous les produits de Sisterly\u00a0Swimwear sont aussi faits \u00e0 partir de filets de p\u00eache recycl\u00e9s. D\u00e9sormais, lorsque vous plongez dans l\u2019oc\u00e9an, vous pouvez ressentir de la fiert\u00e9 en sachant que vous avez aussi aid\u00e9 \u00e0 le nettoyer. \u00ab\u00a0Nos emballages sont aussi compostables. Il suffit donc de les planter dans votre jardin avec un peu de terre et le tour est jou\u00e9\u00a0\u00bb, explique Olivia\u00a0Leger.<\/p>\n<p>\u00ab\u00a0Nous avons toujours \u00e9t\u00e9 passionn\u00e9es par la mode, raconte l\u2019entrepreneure Isabelle Leger. Nous n\u2019arrivions pas toujours \u00e0 trouver des maillots qui \u00e9pousaient les courbes de notre corps pour lui donner l\u2019allure flatteuse que nous recherchions ou qui correspondaient \u00e0 nos valeurs.\u00a0\u00bb En combinant leur amour de la mode, leur int\u00e9r\u00eat pour la protection de l\u2019environnement et leur d\u00e9sir d\u2019inclusion, Olivia et Isabelle ont cr\u00e9\u00e9 leur entreprise pour incarner le changement qu\u2019elles veulent voir dans le monde.<\/p>\n<p>Tout comme Sisterly\u00a0Swimwear, Purolator s\u2019est engag\u00e9e \u00e0 prot\u00e9ger l\u2019environnement et fait tout en son pouvoir pour cr\u00e9er un monde meilleur. Nous sommes ravis de nous associer \u00e0 cette entreprise de maillots de bain durableset \u00e0 ces <a href=\"https:\/\/cloud.connect.purolator.com\/small-business-grants\/2021-winners?lang=fr\" target=\"_blank\" rel=\"noopener\"><u>finalistes du concours de subventions aux petites entreprises \u00ab\u00a0Plein Nord\u00a0\u00bb<\/u><\/a> afin de les aider \u00e0 favoriser l\u2019avenir de leur entreprise.<\/p>\n<p>Vous pouvez regarder toute l\u2019entrevue ici.<\/p>\n<p><iframe title=\"Journ\u00e9e international des femmes avec Sisterly Swimwear\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/EuGO58sI-0E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<a class=\"cta-simple\" href=\"https:\/\/cloud.connect.purolator.com\/shipping-account-benefits\/learn-more?lang=fr&amp;campaign=7014U000002BPHQQA4&amp;utm_campaign=sustainable-swimwear-RCcontent&amp;utm_source=RC&amp;utm_medium=referral&amp;utm_term=RC&amp;utm_content=sustainable-swimwear-rc-article\" target=\"_blank\"><div class=\"text\">\u00cates-vous pr\u00eat \u00e0 offrir une exp\u00e9rience de commerce \u00e9lectronique exceptionnelle? D\u00e9couvrez nos solutions pour les entreprises de vente au d\u00e9tail et en ligne.<\/div><div class=\"cta\">En savoir plus<\/div><\/a>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez comment Sisterly Swim soutient les femmes du monde entier gr\u00e2ce \u00e0 l\u2019inclusion, la durabilit\u00e9 et l\u2019accessibilit\u00e9.<\/p>\n","protected":false},"author":14,"featured_media":4242,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":[43],"meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"learn_about":[83],"bundle":[],"class_list":["post-4230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","learn_about-petit-enterprise","format-article-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inspirer le changement et \u00ab Combattre Les Pr\u00e9jug\u00e9s \u00bb avec une entreprise de maillots de bain durables | Purolator<\/title>\n<meta name=\"description\" content=\"Sisterly Swimwear est une entreprise qui pr\u00f4ne l\u2019accessibilit\u00e9, l\u2019inclusion, la positivit\u00e9 corporelle et le d\u00e9veloppement les maillots de bain durables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inspirer le changement et \u00ab Combattre Les Pr\u00e9jug\u00e9s \u00bb avec une entreprise de maillots de bain durables | Purolator\" \/>\n<meta property=\"og:description\" content=\"Sisterly Swimwear est une entreprise qui pr\u00f4ne l\u2019accessibilit\u00e9, l\u2019inclusion, la positivit\u00e9 corporelle et le d\u00e9veloppement les maillots de bain durables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/\" \/>\n<meta property=\"og:site_name\" content=\"Purolator\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PurolatorInc\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-30T20:30:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-20T17:53:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resources.purolator.com\/wp-content\/uploads\/2022\/03\/Sisterly-swimwear-banner-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ashley Drew\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PurolatorInc\" \/>\n<meta name=\"twitter:site\" content=\"@PurolatorInc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ashley Drew\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inspirer le changement et \u00ab Combattre Les Pr\u00e9jug\u00e9s \u00bb avec une entreprise de maillots de bain durables | Purolator","description":"Sisterly Swimwear est une entreprise qui pr\u00f4ne l\u2019accessibilit\u00e9, l\u2019inclusion, la positivit\u00e9 corporelle et le d\u00e9veloppement les maillots de bain durables.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/","og_locale":"fr_FR","og_type":"article","og_title":"Inspirer le changement et \u00ab Combattre Les Pr\u00e9jug\u00e9s \u00bb avec une entreprise de maillots de bain durables | Purolator","og_description":"Sisterly Swimwear est une entreprise qui pr\u00f4ne l\u2019accessibilit\u00e9, l\u2019inclusion, la positivit\u00e9 corporelle et le d\u00e9veloppement les maillots de bain durables.","og_url":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/","og_site_name":"Purolator","article_publisher":"https:\/\/www.facebook.com\/PurolatorInc","article_published_time":"2022-03-30T20:30:45+00:00","article_modified_time":"2023-10-20T17:53:21+00:00","og_image":[{"width":1500,"height":500,"url":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2022\/03\/Sisterly-swimwear-banner-3.png","type":"image\/png"}],"author":"Ashley Drew","twitter_card":"summary_large_image","twitter_creator":"@PurolatorInc","twitter_site":"@PurolatorInc","twitter_misc":{"\u00c9crit par":"Ashley Drew","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/#article","isPartOf":{"@id":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/"},"author":{"name":"Ashley Drew","@id":"https:\/\/resources.purolator.com\/fr\/#\/schema\/person\/0156d0e9cd2a576638a4b8f27a8a0334"},"headline":"Inspirer le changement et \u00ab Combattre Les Pr\u00e9jug\u00e9s \u00bb avec une entreprise de maillots de bain durables","datePublished":"2022-03-30T20:30:45+00:00","dateModified":"2023-10-20T17:53:21+00:00","mainEntityOfPage":{"@id":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/"},"wordCount":514,"publisher":{"@id":"https:\/\/resources.purolator.com\/fr\/#organization"},"image":{"@id":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/#primaryimage"},"thumbnailUrl":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2022\/03\/Sisterly-swimwear-banner-3.png","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/","url":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/","name":"Inspirer le changement et \u00ab Combattre Les Pr\u00e9jug\u00e9s \u00bb avec une entreprise de maillots de bain durables | Purolator","isPartOf":{"@id":"https:\/\/resources.purolator.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/#primaryimage"},"image":{"@id":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/#primaryimage"},"thumbnailUrl":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2022\/03\/Sisterly-swimwear-banner-3.png","datePublished":"2022-03-30T20:30:45+00:00","dateModified":"2023-10-20T17:53:21+00:00","description":"Sisterly Swimwear est une entreprise qui pr\u00f4ne l\u2019accessibilit\u00e9, l\u2019inclusion, la positivit\u00e9 corporelle et le d\u00e9veloppement les maillots de bain durables.","breadcrumb":{"@id":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/#primaryimage","url":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2022\/03\/Sisterly-swimwear-banner-3.png","contentUrl":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2022\/03\/Sisterly-swimwear-banner-3.png","width":1500,"height":500,"caption":"Sisterly Swimwear"},{"@type":"BreadcrumbList","@id":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/resources.purolator.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Inspirer le changement et \u00ab Combattre Les Pr\u00e9jug\u00e9s \u00bb avec une entreprise de maillots de bain durables"}]},{"@type":"WebSite","@id":"https:\/\/resources.purolator.com\/fr\/#website","url":"https:\/\/resources.purolator.com\/fr\/","name":"Purolator","description":"","publisher":{"@id":"https:\/\/resources.purolator.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resources.purolator.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/resources.purolator.com\/fr\/#organization","name":"Purolator","url":"https:\/\/resources.purolator.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/resources.purolator.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2019\/10\/Purolator-NRS-rgb_JPEG-format.jpg","contentUrl":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2019\/10\/Purolator-NRS-rgb_JPEG-format.jpg","width":393,"height":54,"caption":"Purolator"},"image":{"@id":"https:\/\/resources.purolator.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PurolatorInc","https:\/\/x.com\/PurolatorInc","https:\/\/instagram.com\/purolatorinc","https:\/\/www.linkedin.com\/company\/8948"]},{"@type":"Person","@id":"https:\/\/resources.purolator.com\/fr\/#\/schema\/person\/0156d0e9cd2a576638a4b8f27a8a0334","name":"Ashley Drew","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b42f760fb94f3984e8ed5c0532d98987e3f2bfc2c2fdb1ca9e1117b729eeca88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b42f760fb94f3984e8ed5c0532d98987e3f2bfc2c2fdb1ca9e1117b729eeca88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b42f760fb94f3984e8ed5c0532d98987e3f2bfc2c2fdb1ca9e1117b729eeca88?s=96&d=mm&r=g","caption":"Ashley Drew"}}]}},"wpml_current_locale":"fr_FR","wpml_translations":{"en_US":{"locale":"en_US","id":4227,"slug":"inspiring-change-to-break-the-bias-with-a-sustainable-swimwear-business","post_title":"Inspiring Change to \"Break the Bias\" With a Sustainable Swimwear Business","href":"https:\/\/resources.purolator.com\/inspiring-change-to-break-the-bias-with-a-sustainable-swimwear-business\/"},"fr_FR":{"locale":"fr_FR","id":4230,"slug":"inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables","post_title":"Inspirer le changement et \u00ab Combattre Les Pr\u00e9jug\u00e9s \u00bb avec une entreprise de maillots de bain durables","href":"https:\/\/resources.purolator.com\/fr\/inspirer-le-changement-et-combattre-les-prejuges-avec-une-entreprise-de-maillots-de-bain-durables\/"}},"_links":{"self":[{"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/posts\/4230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/comments?post=4230"}],"version-history":[{"count":0,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/posts\/4230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/media\/4242"}],"wp:attachment":[{"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/media?parent=4230"}],"wp:term":[{"taxonomy":"learn_about","embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/learn_about?post=4230"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/format?post=4230"},{"taxonomy":"bundle","embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/bundle?post=4230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}