{"id":5273,"date":"2023-05-05T12:50:12","date_gmt":"2023-05-05T16:50:12","guid":{"rendered":"https:\/\/resources.purolator.com\/?p=5273"},"modified":"2025-05-06T20:04:23","modified_gmt":"2025-05-07T00:04:23","slug":"les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main","status":"publish","type":"post","link":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/","title":{"rendered":"Les gagnants de la subvention pour petites entreprises de Purolator ont le c\u0153ur sur la main"},"content":{"rendered":"<p>Les quatre\u00a0r\u00e9cipiendaires du concours\u00a02022 de <a href=\"https:\/\/cloud.connect.purolator.com\/small-business-grants?lang=fr\" target=\"_blank\" rel=\"noopener\">subventions aux petites entreprises \u00ab\u00a0Plein Nord\u00a0\u00bb de Purolator<\/a> ont r\u00e9cemment re\u00e7u un prix en argent de 25\u00a0500\u00a0$, dont 5\u00a0000\u00a0$ seront remis \u00e0 une cause qui leur est ch\u00e8re. Avec ce don, ils encouragent les autres \u00e0 donner et prouvent que nous pouvons tous faire une diff\u00e9rence dans la vie des gens. Nous sommes donc fiers de d\u00e9voiler les fa\u00e7ons dont ces gagnants ont choisi de redonner aux collectivit\u00e9s d\u2019ici.<\/p>\n<h2>Des collectivit\u00e9s plus fortes et unies gr\u00e2ce \u00e0 Purolator<\/h2>\n<p>Nos <a href=\"https:\/\/cloud.connect.purolator.com\/grant-winners-2022\/results\" target=\"_blank\" rel=\"noopener\">gagnants<\/a> s\u00e8ment la joie dans les collectivit\u00e9s gr\u00e2ce \u00e0 leurs g\u00e9n\u00e9reux dons.<\/p>\n<h3>EarthPup\u00a0: Offrir \u00e0 nos animaux des g\u00e2teries sant\u00e9 tout en \u00e9liminant le gaspillage alimentaire<\/h3>\n<p><iframe title=\"Le gagnant d\u2019une subventions aux petites entreprises \u00ab Plein Nord \u00bb 2022, Earthpup\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/zCebxLP5X3E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Alors que plus d\u2019un tiers de la nourriture mondiale est gaspill\u00e9e, EarthPup, une entreprise torontoise, s\u2019attaque \u00e0 l\u2019enjeu de la durabilit\u00e9 alimentaire au pays. \u00ab\u00a0Nous transformons des aliments riches en nutriments destin\u00e9s \u00e0 des sites d\u2019enfouissement en de savoureuses g\u00e2teries sant\u00e9 pour chiens. \u00c0 ce jour, nous avons d\u00e9tourn\u00e9 plus de 2\u00a0000\u00a0livres de l\u00e9gumes des sites d\u2019enfouissement\u00a0\u00bb, explique Lucy\u00a0Cullen, fondatrice. Lucy s\u2019associe \u00e0 des entreprises qui partagent les m\u00eames valeurs pour soutenir des organisations torontoises qui veulent mettre fin \u00e0 la pauvret\u00e9 et au gaspillage alimentaires. Lucy donnera \u00e0 <a href=\"https:\/\/www.nudfud.com\/\" target=\"_blank\" rel=\"noopener\">NudFud<\/a>, une entreprise de collations v\u00e9g\u00e9taliennes cherchant \u00e0 cr\u00e9er une cha\u00eene d\u2019approvisionnement qui recyclera la nourriture en produits secs \u00e0 longue dur\u00e9e de conservation.<\/p>\n<a class=\"cta-simple\" href=\"https:\/\/www.facebook.com\/earthpupco\" target=\"_blank\"><div class=\"text\">En savoir plus sur EarthPup<\/div><div class=\"cta\">En savoir plus<\/div><\/a>\n<h3>Westman\u00a0Soil\u00a0Sampling\u00a0: Former les fermiers sur la sant\u00e9 des sols<\/h3>\n<p><iframe title=\"Le gagnant d\u2019une subventions aux petites entreprises \u00ab Plein Nord \u00bb 2022, Westman Soil Sampling\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/9O2J3ZIu99g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Selon Jeremy et Dean, fondateurs, faciliter l\u2019acc\u00e8s \u00e0 l\u2019\u00e9chantillonnage des sols permettra d\u2019offrir des ressources et des connaissances pr\u00e9cieuses aux fermiers, qui pourront en retour profiter de meilleurs revenus tout en optimisant la sant\u00e9 de leurs sols. Le duo explique que \u00ab\u00a0les fermiers peuvent conna\u00eetre la quantit\u00e9 exacte d\u2019engrais dont leurs sols ont besoin, ce qui r\u00e9duit au minimum l\u2019exc\u00e8s de produit qui se retrouve dans les ruisseaux et les autres cours d\u2019eau\u00a0\u00bb. En plus de comprendre l\u2019incidence des sols sur une agriculture saine, Jeremy et Dean savent \u00e0 quel point les camps d\u2019\u00e9t\u00e9 peuvent am\u00e9liorer la vie des enfants. Il remettront leur prix de 5\u00a0000\u00a0$ au <a href=\"https:\/\/wannakumbac.com\/\" target=\"_blank\" rel=\"noopener\">Camp\u00a0Wannakumbac<\/a>, \u00e0 Clear\u00a0Lake, au Manitoba, afin d\u2019honorer le camp d\u2019\u00e9t\u00e9 o\u00f9 ils se sont connus lorsqu\u2019ils avaient neuf\u00a0ans, une rencontre qui a chang\u00e9 leur vie. Gr\u00e2ce \u00e0 ce don, ils esp\u00e8rent donner la possibilit\u00e9 \u00e0 d\u2019autres enfants de nouer de telles amiti\u00e9s, tout en les aidant \u00e0 atteindre leur plein potentiel.<\/p>\n<a class=\"cta-simple\" href=\"https:\/\/www.westmansoil.com\" target=\"_blank\"><div class=\"text\">En savoir plus sur Westman Soil Sampling<\/div><div class=\"cta\">En savoir plus<\/div><\/a>\n<h3>Ruth\u00a0: Faciliter l\u2019acc\u00e8s aux produits menstruels \u00e9cologiques<\/h3>\n<p>Cette entreprise communautaire, qui redonne \u00e0 sa collectivit\u00e9 depuis ses d\u00e9buts, cherche \u00e0 favoriser l\u2019accessibilit\u00e9 aux produits menstruels \u00e9cologiques. Nicole\u00a0Sanchez et Anka\u00a0Chan, fondatrices, expliquent que \u00ab\u00a0les serviettes hygi\u00e9niques jetables et biod\u00e9gradables de Ruth sont une option verte facile \u00e0 adopter\u00a0\u00bb. Ruth s\u2019efforce d\u2019\u00e9liminer les obstacles qui entourent les menstruations et r\u00e9duit le gaspillage en faisant don de plus de 4\u00a0000\u00a0serviettes et en collaborant avec des organismes \u00e0 but non lucratif. L\u2019entreprise s\u2019associe \u00e0 des organisations d\u2019ici pour \u00e9radiquer la pr\u00e9carit\u00e9 menstruelle et offrir des produits menstruels et de l\u2019\u00e9ducation \u00e0 des femmes dans le besoin. C\u2019est \u00e0 cette cause qu\u2019ira son prix \u00ab\u00a0Donner au suivant\u00a0\u00bb de 5\u00a0000\u00a0$.<\/p>\n<a class=\"cta-simple\" href=\"https:\/\/getruth.ca\" target=\"_blank\"><div class=\"text\">En savoir plus sur Ruth<\/div><div class=\"cta\">En savoir plus<\/div><\/a>\n<h3>RoadLoft\u00a0: Profiter de la nature de fa\u00e7on \u00e9coresponsable, sans se ruiner<\/h3>\n<p>Cette prometteuse entreprise qu\u00e9b\u00e9coise con\u00e7oit, produit et distribue des trousses qui transforment temporairement les camionnettes en fourgonnettes de camping s\u00e9curitaires et douillettes. \u00ab\u00a0Depuis nos d\u00e9buts en\u00a02019, nous avons d\u00e9ploy\u00e9 plus de 850\u00a0trousses RoadLoft sur les routes, racontent Laurence\u00a0Dufour et Samuel\u00a0Gauthier, fondateurs. D\u00e9sormais, les nomades automobiles n\u2019ont besoin que d\u2019un v\u00e9hicule, qui offre de multiples fonctions et qui consomme beaucoup moins d\u2019essence.\u00a0\u00bb RoadLoft a \u00e0 c\u0153ur de prot\u00e9ger la nature qui nous entoure. Pour favoriser l\u2019exploration du pays de fa\u00e7on \u00e9cologique, ils remettront donc leur prix de 5\u00a0000\u00a0$ \u00e0 <a href=\"https:\/\/naturequebec.org\/\" target=\"_blank\" rel=\"noopener\">Nature\u00a0Qu\u00e9bec<\/a>, une organisation \u00e0 but non lucratif d\u00e9di\u00e9e \u00e0 la conservation des ressources et des environnements naturels.<\/p>\n<a class=\"cta-simple\" href=\"https:\/\/roadloft.com\/en\" target=\"_blank\"><div class=\"text\">En savoir plus sur RoadLoft<\/div><div class=\"cta\">En savoir plus<\/div><\/a>\n<h2>Ensemble, donnons au suivant<\/h2>\n<p>Nous vous invitons \u00e0 donner au suivant tout au long de l\u2019ann\u00e9e, notamment en prenant part au programme <a href=\"https:\/\/www.purolator.com\/fr\/programme-blitz-contre-la-faim-de-purolator\" target=\"_blank\" rel=\"noopener\">Blitz contre la faim de Purolator<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les quatre\u00a0r\u00e9cipiendaires du concours\u00a02022 de subventions aux petites entreprises \u00ab\u00a0Plein Nord\u00a0\u00bb de Purolator ont r\u00e9cemment re\u00e7u un prix en argent de 25\u00a0500\u00a0$, dont 5\u00a0000\u00a0$ seront remis \u00e0 une cause qui leur est ch\u00e8re. Avec ce don, ils encouragent les autres \u00e0 donner et prouvent que nous pouvons tous faire une diff\u00e9rence dans la vie des [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":5274,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":[43],"meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"learn_about":[83],"bundle":[],"class_list":["post-5273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","learn_about-petit-enterprise","format-article-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les gagnants de la subvention pour petites entreprises de Purolator ont le c\u0153ur sur la main | Purolator<\/title>\n<meta name=\"description\" content=\"Les gagnants du concours \u00ab Plein Nord \u00bb donnent 5 000 $ \u00e0 une organisation de leur choix pour renforcer les collectivit\u00e9s et les entrepreneurs d\u2019ici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les gagnants de la subvention pour petites entreprises de Purolator ont le c\u0153ur sur la main | Purolator\" \/>\n<meta property=\"og:description\" content=\"Les gagnants du concours \u00ab Plein Nord \u00bb donnent 5 000 $ \u00e0 une organisation de leur choix pour renforcer les collectivit\u00e9s et les entrepreneurs d\u2019ici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/\" \/>\n<meta property=\"og:site_name\" content=\"Purolator\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PurolatorInc\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-05T16:50:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-07T00:04:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/resources.purolator.com\/wp-content\/uploads\/2023\/05\/1225_Purolator_SMB_Grant_Giving-Tuesday_Article_Header_FRE_FINAL.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ashley Drew\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PurolatorInc\" \/>\n<meta name=\"twitter:site\" content=\"@PurolatorInc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ashley Drew\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les gagnants de la subvention pour petites entreprises de Purolator ont le c\u0153ur sur la main | Purolator","description":"Les gagnants du concours \u00ab Plein Nord \u00bb donnent 5 000 $ \u00e0 une organisation de leur choix pour renforcer les collectivit\u00e9s et les entrepreneurs d\u2019ici.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/","og_locale":"fr_FR","og_type":"article","og_title":"Les gagnants de la subvention pour petites entreprises de Purolator ont le c\u0153ur sur la main | Purolator","og_description":"Les gagnants du concours \u00ab Plein Nord \u00bb donnent 5 000 $ \u00e0 une organisation de leur choix pour renforcer les collectivit\u00e9s et les entrepreneurs d\u2019ici.","og_url":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/","og_site_name":"Purolator","article_publisher":"https:\/\/www.facebook.com\/PurolatorInc","article_published_time":"2023-05-05T16:50:12+00:00","article_modified_time":"2025-05-07T00:04:23+00:00","og_image":[{"width":2500,"height":1000,"url":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2023\/05\/1225_Purolator_SMB_Grant_Giving-Tuesday_Article_Header_FRE_FINAL.png","type":"image\/png"}],"author":"Ashley Drew","twitter_card":"summary_large_image","twitter_creator":"@PurolatorInc","twitter_site":"@PurolatorInc","twitter_misc":{"\u00c9crit par":"Ashley Drew","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/#article","isPartOf":{"@id":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/"},"author":{"name":"Ashley Drew","@id":"https:\/\/resources.purolator.com\/fr\/#\/schema\/person\/0156d0e9cd2a576638a4b8f27a8a0334"},"headline":"Les gagnants de la subvention pour petites entreprises de Purolator ont le c\u0153ur sur la main","datePublished":"2023-05-05T16:50:12+00:00","dateModified":"2025-05-07T00:04:23+00:00","mainEntityOfPage":{"@id":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/"},"wordCount":827,"publisher":{"@id":"https:\/\/resources.purolator.com\/fr\/#organization"},"image":{"@id":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/#primaryimage"},"thumbnailUrl":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2023\/05\/1225_Purolator_SMB_Grant_Giving-Tuesday_Article_Header_FRE_FINAL.png","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/","url":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/","name":"Les gagnants de la subvention pour petites entreprises de Purolator ont le c\u0153ur sur la main | Purolator","isPartOf":{"@id":"https:\/\/resources.purolator.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/#primaryimage"},"image":{"@id":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/#primaryimage"},"thumbnailUrl":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2023\/05\/1225_Purolator_SMB_Grant_Giving-Tuesday_Article_Header_FRE_FINAL.png","datePublished":"2023-05-05T16:50:12+00:00","dateModified":"2025-05-07T00:04:23+00:00","description":"Les gagnants du concours \u00ab Plein Nord \u00bb donnent 5 000 $ \u00e0 une organisation de leur choix pour renforcer les collectivit\u00e9s et les entrepreneurs d\u2019ici.","breadcrumb":{"@id":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/#primaryimage","url":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2023\/05\/1225_Purolator_SMB_Grant_Giving-Tuesday_Article_Header_FRE_FINAL.png","contentUrl":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2023\/05\/1225_Purolator_SMB_Grant_Giving-Tuesday_Article_Header_FRE_FINAL.png","width":2500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/resources.purolator.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les gagnants de la subvention pour petites entreprises de Purolator ont le c\u0153ur sur la main"}]},{"@type":"WebSite","@id":"https:\/\/resources.purolator.com\/fr\/#website","url":"https:\/\/resources.purolator.com\/fr\/","name":"Purolator","description":"","publisher":{"@id":"https:\/\/resources.purolator.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/resources.purolator.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/resources.purolator.com\/fr\/#organization","name":"Purolator","url":"https:\/\/resources.purolator.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/resources.purolator.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2019\/10\/Purolator-NRS-rgb_JPEG-format.jpg","contentUrl":"https:\/\/resources.purolator.com\/wp-content\/uploads\/2019\/10\/Purolator-NRS-rgb_JPEG-format.jpg","width":393,"height":54,"caption":"Purolator"},"image":{"@id":"https:\/\/resources.purolator.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PurolatorInc","https:\/\/x.com\/PurolatorInc","https:\/\/instagram.com\/purolatorinc","https:\/\/www.linkedin.com\/company\/8948"]},{"@type":"Person","@id":"https:\/\/resources.purolator.com\/fr\/#\/schema\/person\/0156d0e9cd2a576638a4b8f27a8a0334","name":"Ashley Drew","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b42f760fb94f3984e8ed5c0532d98987e3f2bfc2c2fdb1ca9e1117b729eeca88?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b42f760fb94f3984e8ed5c0532d98987e3f2bfc2c2fdb1ca9e1117b729eeca88?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b42f760fb94f3984e8ed5c0532d98987e3f2bfc2c2fdb1ca9e1117b729eeca88?s=96&d=mm&r=g","caption":"Ashley Drew"}}]}},"wpml_current_locale":"fr_FR","wpml_translations":{"en_US":{"locale":"en_US","id":5269,"slug":"purolator-small-business-grant-winners-pay-it-forward","post_title":"Purolator Small Business Grant Winners Pay It Forward","href":"https:\/\/resources.purolator.com\/purolator-small-business-grant-winners-pay-it-forward\/"},"fr_FR":{"locale":"fr_FR","id":5273,"slug":"les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main","post_title":"Les gagnants de la subvention pour petites entreprises de Purolator ont le c\u0153ur sur la main","href":"https:\/\/resources.purolator.com\/fr\/les-gagnants-de-la-subvention-pour-petites-entreprises-de-purolator-ont-le-coeur-sur-la-main\/"}},"_links":{"self":[{"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/posts\/5273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/comments?post=5273"}],"version-history":[{"count":0,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/posts\/5273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/media\/5274"}],"wp:attachment":[{"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/media?parent=5273"}],"wp:term":[{"taxonomy":"learn_about","embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/learn_about?post=5273"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/format?post=5273"},{"taxonomy":"bundle","embeddable":true,"href":"https:\/\/resources.purolator.com\/fr\/wp-json\/wp\/v2\/bundle?post=5273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}